{"id":1316,"date":"2023-03-06T20:33:08","date_gmt":"2023-03-06T20:33:08","guid":{"rendered":"https:\/\/poderemonti.net\/?page_id=1316"},"modified":"2023-03-25T13:45:24","modified_gmt":"2023-03-25T13:45:24","slug":"eventi","status":"publish","type":"page","link":"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/","title":{"rendered":"Eventi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1316\" class=\"elementor elementor-1316 elementor-949\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a45a8bb e-con-full e-con\" data-id=\"a45a8bb\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-898622d elementor-widget elementor-widget-ucaddon_title_hero\" data-id=\"898622d\" data-element_type=\"widget\" data-widget_type=\"ucaddon_title_hero.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Title Hero -->\n\t\t\t<style type=\"text\/css\">\/* widget: Title Hero *\/\n\n#uc_title_hero_elementor14001 *{\n\tbox-sizing: border-box;\n}\n#uc_title_hero_elementor14001{\n\tposition:relative;\n\toverflow:hidden;\n    display:flex;\n    justify-content:center;\n  \talign-items:center;\n    flex-direction: column;\n    background-blend-mode: normal;\n}\n\n#uc_title_hero_elementor14001 .ue_title_hero_container{\n\n    text-align:center;\n    position:relative;\n    z-index:1;\n}\n#uc_title_hero_elementor14001 .ue_title{\n\n\tdisplay:inline-block;\n}\n\n#uc_title_hero_elementor14001 a{\n    display: inline-block;\n    text-align: center;\n\ttext-decoration:none;\n}\n\n#uc_title_hero_elementor14001 .ue_title_hero_overlay\n{\n  position:absolute;\n  top:0;\n  bottom:0;\n  left:0;\n  right:0;\n}\n\n.ue_title\n{\n  font-size:52px;\n}\n\n<\/style>\n\n\t\t\t<div class=\"ue_title_hero\" id=\"uc_title_hero_elementor14001\">\n    <div class=\"ue_title_hero_overlay\"><\/div>\n    <div class=\"ue_title_hero_container\">\n      \t    \t<div class=\"ue_title\"><\/div>\n        <div><\/div>\n              \n        \t\n      \n            <\/div>\n<\/div>\n\t\t\t<!-- end Title Hero -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4874bc03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4874bc03\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-450e9a55\" data-id=\"450e9a55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-790cdf8a elementor-widget elementor-widget-text-editor\" data-id=\"790cdf8a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.4 - 12-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-0f98146 e-con-boxed e-con\" data-id=\"0f98146\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8564a24 elementor-widget elementor-widget-ucaddon_post_grid\" data-id=\"8564a24\" data-element_type=\"widget\" data-widget_type=\"ucaddon_post_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Post Grid -->\n\t\t<link id='font-awesome-css' href='https:\/\/monti1824.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/monti1824.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-v4-shims.css' type='text\/css' rel='stylesheet' >\n\n\t\t\t<style type=\"text\/css\">\/* widget: Post Grid *\/\n\n\n\n#uc_post_grid_elementor25697.uc_post_grid_style_one .uc_post_grid_style_one_wrap {\n   display:grid;\n}\n\n\n\n#uc_post_grid_elementor25697 .uc_post_grid_style_one_item\n{\n  overflow:hidden;\n  position:relative;\n}\n\n#uc_post_grid_elementor25697 .uc_post_image\n{\n  transition:0.3s;\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_post_grid_elementor25697 .uc_post_image img\n{\n  width:100%;\n  display:block;\n  transition:0.3s;\n}\n\n\n\t\n\n\n\n\n\n\n#uc_post_grid_elementor25697 .uc_post_image_overlay\n{\n  position:absolute;\n  top:0px;\n  left:0px;\n  height:100%;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor25697 .uc_more_btn{\n\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n.ue-grid-item-category a\n{\n  display:inline-block;\n  font-size:10px;\n  \n}\n\n.uc_post_title\n{\n  font-size:21px;\n}\n\n\n#uc_post_grid_elementor25697 .ue_post_grid_item\n{\n  display:flex;\n  flex-direction:column;\n}\n\n#uc_post_grid_elementor25697.uc_post_grid_style_one .uc_content{\n flex-grow:1;\n}\n\n#uc_post_grid_elementor25697.uc_post_grid_style_one .uc_content > div\n{\n  height:100%;\n  display:flex;\n  flex-direction:column;\n}\n\n#uc_post_grid_elementor25697 .uc_post_button\n{\n  margin-top:auto;\n}\n\n\n\n\n\n\n\t#uc_post_grid_elementor25697.uc_post_grid_style_one .uc_content{\n     margin-left:20px;\n      margin-right:20px;\n      margin-top:-30px;\n      position:relative;\n    }\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n#uc_post_grid_elementor25697 .ue-meta-data\n{\n  \n  display:flex;\n\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_grid_elementor25697 .ue-grid-item-meta-data\n{\n      display:inline-flex;\n      align-items:center;\n}\n\n#uc_post_grid_elementor25697 .ue-grid-item-meta-data a{\n  color:inherit;\n}\n\n.ue-grid-item-meta-data\n{\n  font-size:12px;\n}\n\n#uc_post_grid_elementor25697 .ue-grid-item-meta-data-icon\n{\n  line-height:1em;\n}\n\n#uc_post_grid_elementor25697 .ue-grid-item-meta-data-icon svg\n{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_grid_elementor25697 .ue-debug-meta\n{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc_post_grid_style_one \" id=\"uc_post_grid_elementor25697\"  >\n\t\t<div class=\"uc_post_grid_style_one_wrap ue_post_grid uc-items-wrapper\">\n\t\t\t<div class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item elementor-animation-grow\">\n  \n   <a class=\"uc_post_grid_style_one_image\" href=\"https:\/\/monti1824.com\/it\/event\/borgo-nero\/\" target=\"_self\">\n   <div class=\"uc_post_image\">\n   <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/07\/borgo-nero-1.jpg\"  src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/07\/borgo-nero-1.jpg\" alt=\"borgo-nero-1\" width=\"945\" height=\"630\">\n   <div class=\"uc_post_image_overlay\"><\/div>\n   <\/div>\n  <\/a>\n   \n <div class=\"uc_content\">\n    <div>\n      \n           \n    \n  \n      \n      \n    <div class=\"uc_post_title\"><a href=\"https:\/\/monti1824.com\/it\/event\/borgo-nero\/\" target=\"_self\"><div>BORGO NERO<\/div><\/a><\/div>\t\n    \n     \n     \n          <div class=\"ue-meta-data\">\n                        \n                        \n        \n\t\t\t\n\n\n            \n                        \t \n          \t\t\n            \t            \n            \t<div class=\"ue-grid-item-meta-data\"><span class=\"ue-grid-item-meta-data-icon\"><i class='far fa-calendar-alt'><\/i><\/span> Fino al:  21\/07\/2024<\/div>\n                        \n                        \n                        \n                        \n            \t\t\t\n              \n            \n          <\/div>\n     \n      \n      \n      \n     <div class=\"uc_post_text\">Peculiare e suggestiva manifestazione dedicata al mondo della stregoneria e del mistero. Il centro storico...<\/div>    <div class=\"uc_post_button\"><a class=\"uc_more_btn \" href=\"https:\/\/monti1824.com\/it\/event\/borgo-nero\/\" target=\"_self\" href='https:\/\/monti1824.com\/it\/event\/borgo-nero\/'>Scopri di pi\u00f9<\/a><\/div> \t<\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item elementor-animation-grow\">\n  \n   <a class=\"uc_post_grid_style_one_image\" href=\"https:\/\/monti1824.com\/it\/event\/palio-di-casole-delsa\/\" target=\"_self\">\n   <div class=\"uc_post_image\">\n   <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/07\/palio-casole-1-1024x682.jpg\"  src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/07\/palio-casole-1-1024x682.jpg\" alt=\"palio-casole-1\" width=\"1024\" height=\"682\">\n   <div class=\"uc_post_image_overlay\"><\/div>\n   <\/div>\n  <\/a>\n   \n <div class=\"uc_content\">\n    <div>\n      \n           \n    \n  \n      \n      \n    <div class=\"uc_post_title\"><a href=\"https:\/\/monti1824.com\/it\/event\/palio-di-casole-delsa\/\" target=\"_self\"><div>PALIO DI CASOLE D'ELSA<\/div><\/a><\/div>\t\n    \n     \n     \n          <div class=\"ue-meta-data\">\n                        \n                        \n        \n\t\t\t\n\n\n            \n                        \t \n          \t\t\n            \t            \n            \t<div class=\"ue-grid-item-meta-data\"><span class=\"ue-grid-item-meta-data-icon\"><i class='far fa-calendar-alt'><\/i><\/span> Fino al:  09\/07\/2023<\/div>\n                        \n                        \n                        \n                        \n            \t\t\t\n              \n            \n          <\/div>\n     \n      \n      \n      \n     <div class=\"uc_post_text\">Antico evento seguito con grande partecipazione dalla popolazione locale e non solo. Il Palio di Casole...<\/div>    <div class=\"uc_post_button\"><a class=\"uc_more_btn \" href=\"https:\/\/monti1824.com\/it\/event\/palio-di-casole-delsa\/\" target=\"_self\" href='https:\/\/monti1824.com\/it\/event\/palio-di-casole-delsa\/'>Scopri di pi\u00f9<\/a><\/div> \t<\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item elementor-animation-grow\">\n  \n   <a class=\"uc_post_grid_style_one_image\" href=\"https:\/\/monti1824.com\/it\/event\/praesepivm-dicembre-casole-delsa\/\" target=\"_self\">\n   <div class=\"uc_post_image\">\n   <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/preasepium_casole-1024x545.jpg\"  src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/preasepium_casole-1024x545.jpg\" alt=\"preasepium_casole\" width=\"1024\" height=\"545\">\n   <div class=\"uc_post_image_overlay\"><\/div>\n   <\/div>\n  <\/a>\n   \n <div class=\"uc_content\">\n    <div>\n      \n           \n    \n  \n      \n      \n    <div class=\"uc_post_title\"><a href=\"https:\/\/monti1824.com\/it\/event\/praesepivm-dicembre-casole-delsa\/\" target=\"_self\"><div>PREASEPIVM - Dicembre<\/div><\/a><\/div>\t\n    \n     \n     \n          <div class=\"ue-meta-data\">\n                        \n                        \n        \n\t\t\t\n\n\n            \n                        \t \n          \t\t\n            \t            \n            \t<div class=\"ue-grid-item-meta-data\"><span class=\"ue-grid-item-meta-data-icon\"><i class='far fa-calendar-alt'><\/i><\/span> Fino al:  28\/02\/2025<\/div>\n                        \n                        \n                        \n                        \n            \t\t\t\n              \n            \n          <\/div>\n     \n      \n      \n      \n     <div class=\"uc_post_text\">Praesepivm \u00e8 il grande spettacolo all&#8217;aperto della nativit\u00e0. Un vero e proprio colossal che coinvolge...<\/div>    <div class=\"uc_post_button\"><a class=\"uc_more_btn \" href=\"https:\/\/monti1824.com\/it\/event\/praesepivm-dicembre-casole-delsa\/\" target=\"_self\" href='https:\/\/monti1824.com\/it\/event\/praesepivm-dicembre-casole-delsa\/'>Scopri di pi\u00f9<\/a><\/div> \t<\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item elementor-animation-grow\">\n  \n   <a class=\"uc_post_grid_style_one_image\" href=\"https:\/\/monti1824.com\/it\/event\/castello-di-casole-visita\/\" target=\"_self\">\n   <div class=\"uc_post_image\">\n   <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/palio-casole-3-1024x678.jpg\"  src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/palio-casole-3-1024x678.jpg\" alt=\"la rocca di Casole d&#039;elsa in notturna\" width=\"1024\" height=\"678\">\n   <div class=\"uc_post_image_overlay\"><\/div>\n   <\/div>\n  <\/a>\n   \n <div class=\"uc_content\">\n    <div>\n      \n           \n    \n  \n      \n      \n    <div class=\"uc_post_title\"><a href=\"https:\/\/monti1824.com\/it\/event\/castello-di-casole-visita\/\" target=\"_self\"><div>Visita alla Torre del Castello di Casole<\/div><\/a><\/div>\t\n    \n     \n     \n          <div class=\"ue-meta-data\">\n                        \n                        \n        \n\t\t\t\n\n\n            \n                        \t \n          \t\t\n            \t            \n            \t<div class=\"ue-grid-item-meta-data\"><span class=\"ue-grid-item-meta-data-icon\"><i class='far fa-calendar-alt'><\/i><\/span> Fino al:  19\/07\/2024<\/div>\n                        \n                        \n                        \n                        \n            \t\t\t\n              \n            \n          <\/div>\n     \n      \n      \n      \n     <div class=\"uc_post_text\">Visitate gratuitamente la torre dell&#8217;antico castello medievale di Casole e godetevi la vista panoramica...<\/div>    <div class=\"uc_post_button\"><a class=\"uc_more_btn \" href=\"https:\/\/monti1824.com\/it\/event\/castello-di-casole-visita\/\" target=\"_self\" href='https:\/\/monti1824.com\/it\/event\/castello-di-casole-visita\/'>Scopri di pi\u00f9<\/a><\/div> \t<\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item elementor-animation-grow\">\n  \n   <a class=\"uc_post_grid_style_one_image\" href=\"https:\/\/monti1824.com\/it\/event\/processione-storica-venerdi-santo\/\" target=\"_self\">\n   <div class=\"uc_post_image\">\n   <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/processione-storica-casole-delsa-601x1024.jpg\"  src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/processione-storica-casole-delsa-601x1024.jpg\" alt=\"processione storica Casole d&#039;elsa\" width=\"601\" height=\"1024\">\n   <div class=\"uc_post_image_overlay\"><\/div>\n   <\/div>\n  <\/a>\n   \n <div class=\"uc_content\">\n    <div>\n      \n           \n    \n  \n      \n      \n    <div class=\"uc_post_title\"><a href=\"https:\/\/monti1824.com\/it\/event\/processione-storica-venerdi-santo\/\" target=\"_self\"><div>PROCESSIONE STORICA DEL VENERDI' SANTO<\/div><\/a><\/div>\t\n    \n     \n     \n          <div class=\"ue-meta-data\">\n                        \n                        \n        \n\t\t\t\n\n\n            \n                        \t \n          \t\t\n            \t            \n            \t<div class=\"ue-grid-item-meta-data\"><span class=\"ue-grid-item-meta-data-icon\"><i class='far fa-calendar-alt'><\/i><\/span> Fino al:  10\/05\/2024<\/div>\n                        \n                        \n                        \n                        \n            \t\t\t\n              \n            \n          <\/div>\n     \n      \n      \n      \n     <div class=\"uc_post_text\">La processione del Venerd\u00ec Santo si tasforma in corteo storico di grande pregio . Alla luce delle torce...<\/div>    <div class=\"uc_post_button\"><a class=\"uc_more_btn \" href=\"https:\/\/monti1824.com\/it\/event\/processione-storica-venerdi-santo\/\" target=\"_self\" href='https:\/\/monti1824.com\/it\/event\/processione-storica-venerdi-santo\/'>Scopri di pi\u00f9<\/a><\/div> \t<\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item elementor-animation-grow\">\n  \n   <a class=\"uc_post_grid_style_one_image\" href=\"https:\/\/monti1824.com\/it\/event\/fantasticarte-art-festival-mensano\/\" target=\"_self\">\n   <div class=\"uc_post_image\">\n   <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/fantasticarte.jpg\"  src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/fantasticarte.jpg\" alt=\"fantasticarte\" width=\"630\" height=\"453\">\n   <div class=\"uc_post_image_overlay\"><\/div>\n   <\/div>\n  <\/a>\n   \n <div class=\"uc_content\">\n    <div>\n      \n           \n    \n  \n      \n      \n    <div class=\"uc_post_title\"><a href=\"https:\/\/monti1824.com\/it\/event\/fantasticarte-art-festival-mensano\/\" target=\"_self\"><div>FANTASTICARTE - Art Festival a Mensano - Luglio<\/div><\/a><\/div>\t\n    \n     \n     \n          <div class=\"ue-meta-data\">\n                        \n                        \n        \n\t\t\t\n\n\n            \n                        \t \n          \t\t\n            \t            \n            \t<div class=\"ue-grid-item-meta-data\"><span class=\"ue-grid-item-meta-data-icon\"><i class='far fa-calendar-alt'><\/i><\/span> Fino al:  16\/02\/2024<\/div>\n                        \n                        \n                        \n                        \n            \t\t\t\n              \n            \n          <\/div>\n     \n      \n      \n      \n     <div class=\"uc_post_text\">In un ambiente preservato e circondato da paesaggi e campagne tipicamente toscani, i visitatori potranno...<\/div>    <div class=\"uc_post_button\"><a class=\"uc_more_btn \" href=\"https:\/\/monti1824.com\/it\/event\/fantasticarte-art-festival-mensano\/\" target=\"_self\" href='https:\/\/monti1824.com\/it\/event\/fantasticarte-art-festival-mensano\/'>Scopri di pi\u00f9<\/a><\/div> \t<\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item elementor-animation-grow\">\n  \n   <a class=\"uc_post_grid_style_one_image\" href=\"https:\/\/monti1824.com\/it\/event\/casole-fiorita-flowers-festival-in-casole\/\" target=\"_self\">\n   <div class=\"uc_post_image\">\n   <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/casole-fiorita.jpg\"  src=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/casole-fiorita.jpg\" alt=\"casole fiorita\" width=\"750\" height=\"486\">\n   <div class=\"uc_post_image_overlay\"><\/div>\n   <\/div>\n  <\/a>\n   \n <div class=\"uc_content\">\n    <div>\n      \n           \n    \n  \n      \n      \n    <div class=\"uc_post_title\"><a href=\"https:\/\/monti1824.com\/it\/event\/casole-fiorita-flowers-festival-in-casole\/\" target=\"_self\"><div>CASOLE FIORITA - Festival dei Fiori a Casole - Maggio e Settembre<\/div><\/a><\/div>\t\n    \n     \n     \n          <div class=\"ue-meta-data\">\n                        \n                        \n        \n\t\t\t\n\n\n            \n                        \t \n          \t\t\n            \t            \n            \t<div class=\"ue-grid-item-meta-data\"><span class=\"ue-grid-item-meta-data-icon\"><i class='far fa-calendar-alt'><\/i><\/span> Fino al:  31\/05\/2023<\/div>\n                        \n                        \n                        \n                        \n            \t\t\t\n              \n            \n          <\/div>\n     \n      \n      \n      \n     <div class=\"uc_post_text\">Giunge alla terza edizione l&#8217;evento pi\u00f9 atteso della primavera: Casole Fiorita e &#8220;il senso...<\/div>    <div class=\"uc_post_button\"><a class=\"uc_more_btn \" href=\"https:\/\/monti1824.com\/it\/event\/casole-fiorita-flowers-festival-in-casole\/\" target=\"_self\" href='https:\/\/monti1824.com\/it\/event\/casole-fiorita-flowers-festival-in-casole\/'>Scopri di pi\u00f9<\/a><\/div> \t<\/div>\n  <\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\n\n  <div id=\"uc_post_grid_elementor25697_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No posts found<\/div>\n\n\n\t\t\t<!-- end Post Grid -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PREASEPIVM &#8211; December Fino al: 28\/02\/2025 Praesepivm is the great outdoor show of the nativity. A true colossal that involves a large part of the&#8230; Scopri di pi\u00f9 Visit the medieval tower of the castle in Casole Fino al: 19\/07\/2024 Free visit to the tower of the old Medieval castle in Casole and enyoy the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":953,"parent":1296,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-1316","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eventi a Casole d&#039;Elsa - Agriturismo Monti 1824<\/title>\n<meta name=\"description\" content=\"Eventi a Casole d&#039;Elsa, Siena, Toscana\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eventi a Casole d&#039;Elsa - Agriturismo Monti 1824\" \/>\n<meta property=\"og:description\" content=\"Eventi a Casole d&#039;Elsa, Siena, Toscana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/\" \/>\n<meta property=\"og:site_name\" content=\"Agriturismo Monti 1824\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-25T13:45:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/siena-palio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/\",\"url\":\"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/\",\"name\":\"Eventi a Casole d'Elsa - Agriturismo Monti 1824\",\"isPartOf\":{\"@id\":\"https:\/\/monti1824.com\/it\/#website\"},\"datePublished\":\"2023-03-06T20:33:08+00:00\",\"dateModified\":\"2023-03-25T13:45:24+00:00\",\"description\":\"Eventi a Casole d'Elsa, Siena, Toscana\",\"breadcrumb\":{\"@id\":\"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/monti1824.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Agriturismo\",\"item\":\"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eventi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/monti1824.com\/it\/#website\",\"url\":\"https:\/\/monti1824.com\/it\/\",\"name\":\"Agriturismo Monti 1824\",\"description\":\"Casole D&#039;Elsa\",\"publisher\":{\"@id\":\"https:\/\/monti1824.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/monti1824.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/monti1824.com\/it\/#organization\",\"name\":\"Agriturismo Monti 1824\",\"url\":\"https:\/\/monti1824.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/monti1824.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/07\/logo-r-def.svg\",\"contentUrl\":\"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/07\/logo-r-def.svg\",\"width\":305,\"height\":217,\"caption\":\"Agriturismo Monti 1824\"},\"image\":{\"@id\":\"https:\/\/monti1824.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eventi a Casole d'Elsa - Agriturismo Monti 1824","description":"Eventi a Casole d'Elsa, Siena, Toscana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/","og_locale":"it_IT","og_type":"article","og_title":"Eventi a Casole d'Elsa - Agriturismo Monti 1824","og_description":"Eventi a Casole d'Elsa, Siena, Toscana","og_url":"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/","og_site_name":"Agriturismo Monti 1824","article_modified_time":"2023-03-25T13:45:24+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/03\/siena-palio.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/","url":"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/","name":"Eventi a Casole d'Elsa - Agriturismo Monti 1824","isPartOf":{"@id":"https:\/\/monti1824.com\/it\/#website"},"datePublished":"2023-03-06T20:33:08+00:00","dateModified":"2023-03-25T13:45:24+00:00","description":"Eventi a Casole d'Elsa, Siena, Toscana","breadcrumb":{"@id":"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/eventi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/monti1824.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Agriturismo","item":"https:\/\/monti1824.com\/it\/agriturismo-casole-d-elsa-toscana\/"},{"@type":"ListItem","position":3,"name":"Eventi"}]},{"@type":"WebSite","@id":"https:\/\/monti1824.com\/it\/#website","url":"https:\/\/monti1824.com\/it\/","name":"Agriturismo Monti 1824","description":"Casole D&#039;Elsa","publisher":{"@id":"https:\/\/monti1824.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/monti1824.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/monti1824.com\/it\/#organization","name":"Agriturismo Monti 1824","url":"https:\/\/monti1824.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/monti1824.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/07\/logo-r-def.svg","contentUrl":"https:\/\/monti1824.com\/wp-content\/uploads\/2023\/07\/logo-r-def.svg","width":305,"height":217,"caption":"Agriturismo Monti 1824"},"image":{"@id":"https:\/\/monti1824.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/pages\/1316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/comments?post=1316"}],"version-history":[{"count":8,"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/pages\/1316\/revisions"}],"predecessor-version":[{"id":1520,"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/pages\/1316\/revisions\/1520"}],"up":[{"embeddable":true,"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/pages\/1296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/media\/953"}],"wp:attachment":[{"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/media?parent=1316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/categories?post=1316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monti1824.com\/it\/wp-json\/wp\/v2\/tags?post=1316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}